{"id":9029,"date":"2024-06-22T02:19:23","date_gmt":"2024-06-22T02:19:23","guid":{"rendered":"https:\/\/wordpress-439166-3568869.cloudwaysapps.com\/?p=9029"},"modified":"2024-09-12T15:06:30","modified_gmt":"2024-09-12T15:06:30","slug":"how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi","status":"publish","type":"post","link":"https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/","title":{"rendered":"How an Attorney Gets Paid by Social Security Administration (SSA) for Your Monthly Disability Checks (SSDI and\/or SSI)"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;9031&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;40&#8243; bottom_padding=&#8221;40&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; left_margin_phone=&#8221;2%&#8221; constrain_group_6=&#8221;yes&#8221; right_margin_phone=&#8221;2%&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;How an Attorney Gets Paid by Social Security Administration (SSA)<br \/>\nfor Your Monthly DIsability Checks (SSDI and\/or SSI)&#8221; font_container=&#8221;tag:h2|font_size:36|text_align:center|color:%23003487&#8243; use_theme_fonts=&#8221;yes&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_margin=&#8221;10&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1719024502747{padding-bottom: 0px !important;}&#8221;]If you&#8217;re getting help from an attorney to get Social Security Disability Insurance (SSDI) or Supplemental Security Income (SSI) benefits from the Social Security Administration (SSA) you might wonder how the attorney gets paid.[\/vc_column_text][vc_custom_heading text=&#8221;<strong>Let&#8217;s break it down in simple terms!<\/strong>&#8221; font_container=&#8221;tag:h2|font_size:20|text_align:left|color:%2300ad2e&#8221; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;<strong>Payment for SSDI and SSI Cases<\/strong>&#8221; font_container=&#8221;tag:h2|font_size:26|text_align:left|color:%23003487&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1719024668882{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text]Most attorneys who help with disability claims work on a contingency fee basis. This means they only get <span style=\"text-decoration: underline; text-decoration-color: #34A83F; text-underline-offset: 4px; text-decoration-thickness: 2px;\">paid if they win your case<\/span>. Here\u2019s how it works:[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_margin=&#8221;40&#8243; bottom_margin=&#8221;50&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-12-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-12-percent&#8221; column_padding_position=&#8221;top-bottom&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;8941&#8243; background_image_phone=&#8221;8941&#8243; background_image_position=&#8221;center center&#8221; enable_bg_scale=&#8221;true&#8221; background_image_loading=&#8221;default&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;shadow-img&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;advanced&#8221; column_border_color=&#8221;#003487&#8243; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;<strong>Contingency Fee Basics<br \/>\n<\/strong>&#8221; font_container=&#8221;tag:h2|font_size:26|text_align:left|color:%23003487&#8243; use_theme_fonts=&#8221;yes&#8221;][vc_custom_heading text=&#8221;<strong>No Upfront Fees<\/strong>&#8221; font_container=&#8221;tag:p|font_size:20|text_align:left|color:%2300ad2e&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1719077040074{margin-bottom: -10px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1719077055068{margin-top: 10px !important;margin-bottom: 5px !important;}&#8221;]You don\u2019t pay anything upfront. The attorney only gets paid if your claim is approved.[\/vc_column_text][vc_custom_heading text=&#8221;<strong>Percentage of Back Pay<\/strong>&#8221; font_container=&#8221;tag:p|font_size:20|text_align:left|color:%2300ad2e&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1719077087737{margin-bottom: -10px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1719077096550{margin-top: 10px !important;margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;]The attorney\u2019s fee is usually a percentage of the back pay you receive. The SSA sets limits to make sure fees are fair.[\/vc_column_text][vc_column_text]\n<h4 style=\"color: #54555b; font-size: 22px;\">Questions? Call us at <a style=\"color: #00ad2e; text-decoration: none;\" href=\"tel:1-800-840-4040\">1 800 840-4040<\/a><\/h4>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;<strong>What is Back Pay?<br \/>\n<\/strong>&#8221; font_container=&#8221;tag:h2|font_size:26|text_align:left|color:%23003487&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1719026837135{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text]Backpay for SSDI (Social Security Disability Insurance) payments refers to the <strong>lump sum of money awarded to an individual who has been approved for disability benefits<\/strong>, covering the period from the onset of their disability to the date their benefits were approved. This payment compensates for <strong>the time during which the individual was disabled and eligible for benefits<\/strong> but had not yet received them due to the processing time of their claim.<\/p>\n<p>There is a five-month waiting period from the onset of the disability during which no benefits are paid. Additionally, the backpay can only cover a maximum of 12 months prior to the application date.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;<strong>How Does Back Pay Work?<\/strong><\/p>\n<p>&#8221; font_container=&#8221;tag:h2|font_size:26|text_align:left|color:%23003487&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1719026885532{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text]<strong><span style=\"color: #00ad2e;\">Filing Your Claim:<\/span><\/strong> When you apply for disability benefits, the SSA looks at the date you became unable to work due to your disability. This is called your &#8220;disability onset date.&#8221; Note that this date may be different from when you first submitted your application for benefits. You are only eligible to receive benefits up to the first 12 months before the filing of your initial application, so it is advantageous to file as soon as you know you\u2019re not going to be able to return to work.<\/p>\n<p><strong><span style=\"color: #00ad2e;\">Waiting Period:<\/span><\/strong> There is a mandatory 5-month waiting period from your disability onset date before you can start receiving your monthly disability check. This means you won&#8217;t receive benefits for the first five months after the established SSA \u201cdisability onset date.\u201d<\/p>\n<p><strong><span style=\"color: #00ad2e;\">Approval Time:<\/span><\/strong> It often takes many months (sometimes over a year) for the SSA to review and approve your claim. During this time, no payments are made to you, but this waiting period is being tracked and will be used by SSA to determine your back pay.<\/p>\n<p><strong><span style=\"color: #54555b;\">Example:<\/span><\/strong><\/p>\n<ul>\n<li>Disability Onset Date: January 1, 2023<\/li>\n<li>Waiting Period: January 1 &#8211; May 31, 2023 (no retroactive payment)<\/li>\n<li>Approval Date: February 1, 2024. This means that your \u201cretroactive initial payment\u201d includes payments from June 1, 2023 to your approval date in this example, February 1, 2024.<\/li>\n<\/ul>\n[\/vc_column_text][vc_column_text]In this example, you would be eligible for back pay from June 1, 2023 to February 1, 2024. Your total back pay will be the amount you receive monthly from the SSA multiplied by the number of months the SSA was late to review your application. In this case, if you receive $1,000 per month, we multiply it by 8 months to obtain a retroactive payment of $8,000.00[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;<strong>SSA Fee Limits<\/strong><\/p>\n<p>&#8221; font_container=&#8221;tag:h2|font_size:26|text_align:left|color:%23003487&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1719030031875{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1719076328257{margin-bottom: 20px !important;}&#8221;]The SSA says the maximum fee the attorney can get is 25% of your back pay or $7,200, <span style=\"text-decoration: underline; text-decoration-color: #34A83F; text-underline-offset: 4px; text-decoration-thickness: 2px;\">whichever is less.<\/span>[\/vc_column_text][vc_row_inner content_placement=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;center&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1719034878009{margin-top: 20px !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;<strong>If you get $10,000<\/strong><\/p>\n<p>&#8221; font_container=&#8221;tag:h2|font_size:22|text_align:center|color:%23003487&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1719031446301{margin-bottom: -5px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1719031454572{margin-bottom: 5px !important;padding-bottom: 0px !important;}&#8221;]\n<p style=\"text-align: center;\">in back pay, the attorney can get<\/p>\n[\/vc_column_text][heading]\n<div style=\"width: 100%; display: flex; justify-content: center;\">\n<div id=\"ratetxt\" style=\"color: white; background-color: #00ad2e; padding: 0px 10px; border-radius: 50px; width: 200px; display: inline-block; text-align: center; font-size: 26px;\">25%<\/div>\n<\/div>\n[\/heading][vc_column_text css=&#8221;.vc_custom_1719031700408{margin-top: -10px !important;margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;]\n<p style=\"text-align: center;\">of that back pay, which is $2,500.<\/p>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;<strong>If you get $40,000<\/strong><\/p>\n<p>&#8221; font_container=&#8221;tag:h2|font_size:22|text_align:center|color:%23003487&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1719031626097{margin-bottom: -5px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1719031641876{margin-bottom: 5px !important;padding-bottom: 0px !important;}&#8221;]\n<p style=\"text-align: center;\">in back pay, the attorney can get up to<\/p>\n[\/vc_column_text][heading]\n<div style=\"width: 100%; display: flex; justify-content: center;\">\n<div id=\"ratetxt\" style=\"color: white; background-color: #00ad2e; padding: 0px 10px; border-radius: 50px; width: 200px; display: inline-block; text-align: center; font-size: 26px;\">$7,200<\/div>\n<\/div>\n[\/heading][vc_column_text css=&#8221;.vc_custom_1719031690219{margin-top: -10px !important;margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;]\n<p style=\"text-align: center;\">because 25% of $40,000 is $10,000, and $7,200 is less than that.<\/p>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;2%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;2%&#8221; left_padding_desktop=&#8221;2%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;2%&#8221; bottom_margin=&#8221;-250&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;999&#8243; overflow=&#8221;visible&#8221; class=&#8221;shadow&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;<strong>How the Attorney Gets Paid<\/strong><\/p>\n<p>&#8221; font_container=&#8221;tag:h2|font_size:26|text_align:left|color:%23003487&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1719035116486{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text]<strong><span style=\"color: #00ad2e;\">Direct Payment:<\/span><\/strong> The SSA pays the attorney directly from your back pay. This makes it easy for you.<\/p>\n<p>Example: If you get $10,000 in back pay and the attorney\u2019s fee is $2,500, the SSA sends $2,500 to the attorney and $7,500 to you.[\/vc_column_text][vc_column_text]<strong><span style=\"color: #00ad2e;\">Fee Agreement:<\/span><\/strong> You and the attorney sign a fee agreement, which the SSA must approve. This agreement explains how much the attorney will be paid.[\/vc_column_text][vc_column_text]<strong><span style=\"color: #00ad2e;\">Fee Petition:<\/span><\/strong> If there is no back pay or there are special circumstances, the attorney can ask SSA to approve a different rate through a fee request.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-9-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; background_image=&#8221;9052&#8243; background_image_phone=&#8221;9052&#8243; background_image_position=&#8221;right center&#8221; enable_bg_scale=&#8221;true&#8221; background_image_loading=&#8221;default&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f1f5f9&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;300&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;<strong>What If There\u2019s No Back Pay?<\/strong><\/p>\n<p>&#8221; font_container=&#8221;tag:h2|font_size:26|text_align:left|color:%23003487&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1719071957649{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text]If there\u2019s no back pay, the attorney might still get paid, but if the attorney chooses to do so, he\/she can file a fee petition, showing the work they did and asking the SSA to approve their payment.[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1719072767487{padding-top: 20px !important;padding-bottom: 50px !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/casadelajusticia.com\/en\/wp-content\/uploads\/2024\/06\/blog1-icon2-1-300x300.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<h4 style=\"color: #34a83f; font-size: 22px;\">Alternative Agreements:<\/h4>\n<p>Some attorneys have other payment plans, such as a flat fee or hourly fee. These need to be approved by the SSA. <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <img decoding=\"async\" src=\"https:\/\/casadelajusticia.com\/en\/wp-content\/uploads\/2024\/06\/blog1-icon-300x300.png\" alt=\"\" \/> <\/div><div class=\"iwt-text\"> \n<h4 style=\"color: #34a83f; font-size: 22px;\">Fee Petition:<\/h4>\n<p>The attorney can file a fee petition, showing the work he or she performed and asking SSA to approve payment. <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_margin=&#8221;40&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;<strong>Additional Costs<\/strong><\/p>\n<p>&#8221; font_container=&#8221;tag:h2|font_size:26|text_align:left|color:%23003487&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1719072844648{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text]Sometimes there are extra costs, like fees for getting medical records or mailing documents. These should be explained in your agreement with the attorney.<strong><span style=\"color: #00ad2e;\"> At House of Justice we do not charge for any of these extra costs.<\/span><\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color=&#8221;#f1f5f9&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][vc_custom_heading text=&#8221;<strong>Summary<\/strong><\/p>\n<p>&#8221; font_container=&#8221;tag:h2|font_size:26|text_align:center|color:%23003487&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1719074416687{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1719074500818{margin-top: -30px !important;}&#8221;]<strong><span style=\"color: #00ad2e;\">No Upfront Payment: <\/span><\/strong>Attorneys usually don\u2019t charge you upfront.<\/p>\n<p><strong><span style=\"color: #00ad2e;\">Contingency Fee: <\/span><\/strong>They get a percentage of your back pay, up to 25% or $7,200, whichever is less.[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]<strong><span style=\"color: #00ad2e;\">Direct Payment: <\/span><\/strong>The SSA pays the attorney directly from your back pay.<\/p>\n<p><strong><span style=\"color: #00ad2e;\">No Back Pay: <\/span><\/strong>If there\u2019s no back pay, the attorney might file a fee petition.[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_margin=&#8221;40&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_custom_heading text=&#8221;<strong>Conclusion<\/strong><\/p>\n<p>&#8221; font_container=&#8221;tag:h2|font_size:26|text_align:left|color:%23003487&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1719074622066{margin-bottom: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column_text]Working with an attorney can help make the process smoother and improve your chances of getting approved. If you need to file your first application or if you\u2019ve already been denied by SSA and need to file an appeal, we are here to help. Just call us at 1 800-840-4040[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;10&#8243; bottom_padding=&#8221;50&#8243; bottom_margin=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h6 style=\"font-size: 35px; color: #00ad2e; text-align: center; line-height: 1.2;\"><em><strong>WINNING<\/strong> begins with a <strong>CALL<\/strong><\/em><\/h6>\n[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1712182202776{margin-top: 30px !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_btn size=&#8221;jumbo&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;blog-button&#8221; text=&#8221;1 800 840 4040&#8243; url=&#8221;tel:+12097800906&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;9063&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;40&#8243; bottom_padding=&#8221;40&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_highlighted_text color_type=&#8221;regular&#8221; style=&#8221;full_text&#8221; highlight_expansion=&#8221;default&#8221;]\n<h1 style=\"font-weight: 900; text-align: center;\"><span style=\"color: #00ad2e;\">House of Justice<\/span><\/h1>\n<p style=\"text-align: center;\"><span style=\"color: #00ad2e; font-size: 24px; font-style: italic;\">your lawyers for all your legal situations<br \/>\n<\/span>[\/nectar_highlighted_text][nectar_icon_list color=&#8221;Accent-Color&#8221; direction=&#8221;vertical&#8221; icon_size=&#8221;small&#8221; icon_style=&#8221;no-border&#8221;][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;html&#8221; title=&#8221;List Item&#8221; id=&#8221;1712178208-1-71&#8243; icon_fontawesome=&#8221;fa fa-square&#8221;]<span style=\"color: #000000;\">Does any of your family members or a friend with a disability need to apply for a monthly Social Security Disability check?<br \/>\n<\/span>[\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;html&#8221; title=&#8221;List Item&#8221; id=&#8221;1712178208-1-71&#8243; icon_fontawesome=&#8221;fa fa-square&#8221;]<span style=\"color: #000000;\">Have you or any of your family members been involved in a work accident, had a car accident, or a slip and fall accident in a public place?<br \/>\n<\/span>[\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;html&#8221; title=&#8221;List Item&#8221; id=&#8221;1712178208-1-71&#8243; icon_fontawesome=&#8221;fa fa-square&#8221;]<span style=\"color: #000000;\">Do you have any problems with your weekly payment at work, or are you not being paid overtime, sexually harassed or wrongfully terminated?<\/span>[\/nectar_icon_list_item][nectar_icon_list_item icon_type=&#8221;icon&#8221; text_full_html=&#8221;html&#8221; title=&#8221;List Item&#8221; id=&#8221;1712178208-1-71&#8243; icon_fontawesome=&#8221;fa fa-square&#8221;]<span style=\"color: #000000;\">In the last 3 years, have you or your family had a case of medical negligence that resulted in a serious injury or death?<br \/>\n<\/span>[\/nectar_icon_list_item][\/nectar_icon_list][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h4 style=\"text-align: center;\"><strong style=\"font-size: 22px;\">You may be entitled to monetary compensation<br \/>\n<\/strong><\/h4>\n[\/vc_column_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221; css=&#8221;.vc_custom_1712182202776{margin-top: 30px !important;}&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][nectar_btn size=&#8221;jumbo&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; el_class=&#8221;blog-button&#8221; text=&#8221;1 800 840 4040&#8243; url=&#8221;tel:+12097800906&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":9031,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-9029","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sin-categorizar"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>How an Attorney Gets Paid by Social Security Administration (SSA) for Your Monthly Disability Checks (SSDI and\/or SSI) | Casadelajusticia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How an Attorney Gets Paid by Social Security Administration (SSA) for Your Monthly Disability Checks (SSDI and\/or SSI)\" \/>\n<meta property=\"og:description\" content=\"If you&#039;re getting help from an attorney to get Social Security Disability Insurance (SSDI) or Supplemental Security Income (SSI) benefits from the Social\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/\" \/>\n<meta property=\"og:site_name\" content=\"Casadelajusticia\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-22T02:19:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-12T15:06:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casadelajusticia.com\/en\/wp-content\/uploads\/2024\/06\/blog1-image1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2224\" \/>\n\t<meta property=\"og:image:height\" content=\"816\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"28 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/#\\\/schema\\\/person\\\/ed27935e9f623626b401bf0b6f426de3\"},\"headline\":\"How an Attorney Gets Paid by Social Security Administration (SSA) for Your Monthly Disability Checks (SSDI and\\\/or SSI)\",\"datePublished\":\"2024-06-22T02:19:23+00:00\",\"dateModified\":\"2024-09-12T15:06:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\\\/\"},\"wordCount\":5619,\"publisher\":{\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/blog1-image1.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\\\/\",\"url\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\\\/\",\"name\":\"How an Attorney Gets Paid by Social Security Administration (SSA) for Your Monthly Disability Checks (SSDI and\\\/or SSI) | Casadelajusticia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/blog1-image1.jpg\",\"datePublished\":\"2024-06-22T02:19:23+00:00\",\"dateModified\":\"2024-09-12T15:06:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/blog1-image1.jpg\",\"contentUrl\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/blog1-image1.jpg\",\"width\":2224,\"height\":816},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How an Attorney Gets Paid by Social Security Administration (SSA) for Your Monthly Disability Checks (SSDI and\\\/or SSI)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/\",\"name\":\"Casadelajusticia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/#organization\",\"name\":\"Casa de la Justicia\",\"url\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/change-logo.png\",\"contentUrl\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/change-logo.png\",\"width\":190,\"height\":92,\"caption\":\"Casa de la Justicia\"},\"image\":{\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/#\\\/schema\\\/person\\\/ed27935e9f623626b401bf0b6f426de3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1fc7b510198e711d1eda76e5bd3197552d24dd61a7e925c04c4bd16c63362d5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1fc7b510198e711d1eda76e5bd3197552d24dd61a7e925c04c4bd16c63362d5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b1fc7b510198e711d1eda76e5bd3197552d24dd61a7e925c04c4bd16c63362d5?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/casadelajusticia.com\\\/en\"],\"url\":\"https:\\\/\\\/casadelajusticia.com\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"How an Attorney Gets Paid by Social Security Administration (SSA) for Your Monthly Disability Checks (SSDI and\/or SSI) | Casadelajusticia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/","og_locale":"en_US","og_type":"article","og_title":"How an Attorney Gets Paid by Social Security Administration (SSA) for Your Monthly Disability Checks (SSDI and\/or SSI)","og_description":"If you're getting help from an attorney to get Social Security Disability Insurance (SSDI) or Supplemental Security Income (SSI) benefits from the Social","og_url":"https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/","og_site_name":"Casadelajusticia","article_published_time":"2024-06-22T02:19:23+00:00","article_modified_time":"2024-09-12T15:06:30+00:00","og_image":[{"width":2224,"height":816,"url":"https:\/\/casadelajusticia.com\/en\/wp-content\/uploads\/2024\/06\/blog1-image1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"28 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/#article","isPartOf":{"@id":"https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/"},"author":{"name":"admin","@id":"https:\/\/casadelajusticia.com\/en\/#\/schema\/person\/ed27935e9f623626b401bf0b6f426de3"},"headline":"How an Attorney Gets Paid by Social Security Administration (SSA) for Your Monthly Disability Checks (SSDI and\/or SSI)","datePublished":"2024-06-22T02:19:23+00:00","dateModified":"2024-09-12T15:06:30+00:00","mainEntityOfPage":{"@id":"https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/"},"wordCount":5619,"publisher":{"@id":"https:\/\/casadelajusticia.com\/en\/#organization"},"image":{"@id":"https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/#primaryimage"},"thumbnailUrl":"https:\/\/casadelajusticia.com\/en\/wp-content\/uploads\/2024\/06\/blog1-image1.jpg","articleSection":["Sin categorizar"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/","url":"https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/","name":"How an Attorney Gets Paid by Social Security Administration (SSA) for Your Monthly Disability Checks (SSDI and\/or SSI) | Casadelajusticia","isPartOf":{"@id":"https:\/\/casadelajusticia.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/#primaryimage"},"image":{"@id":"https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/#primaryimage"},"thumbnailUrl":"https:\/\/casadelajusticia.com\/en\/wp-content\/uploads\/2024\/06\/blog1-image1.jpg","datePublished":"2024-06-22T02:19:23+00:00","dateModified":"2024-09-12T15:06:30+00:00","breadcrumb":{"@id":"https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/#primaryimage","url":"https:\/\/casadelajusticia.com\/en\/wp-content\/uploads\/2024\/06\/blog1-image1.jpg","contentUrl":"https:\/\/casadelajusticia.com\/en\/wp-content\/uploads\/2024\/06\/blog1-image1.jpg","width":2224,"height":816},{"@type":"BreadcrumbList","@id":"https:\/\/casadelajusticia.com\/en\/how-an-attorney-gets-paid-by-social-security-administration-ssa-for-your-monthly-disability-checks-ssdi-and-or-ssi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadelajusticia.com\/en\/"},{"@type":"ListItem","position":2,"name":"How an Attorney Gets Paid by Social Security Administration (SSA) for Your Monthly Disability Checks (SSDI and\/or SSI)"}]},{"@type":"WebSite","@id":"https:\/\/casadelajusticia.com\/en\/#website","url":"https:\/\/casadelajusticia.com\/en\/","name":"Casadelajusticia","description":"","publisher":{"@id":"https:\/\/casadelajusticia.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadelajusticia.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/casadelajusticia.com\/en\/#organization","name":"Casa de la Justicia","url":"https:\/\/casadelajusticia.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casadelajusticia.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/casadelajusticia.com\/en\/wp-content\/uploads\/2022\/07\/change-logo.png","contentUrl":"https:\/\/casadelajusticia.com\/en\/wp-content\/uploads\/2022\/07\/change-logo.png","width":190,"height":92,"caption":"Casa de la Justicia"},"image":{"@id":"https:\/\/casadelajusticia.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casadelajusticia.com\/en\/#\/schema\/person\/ed27935e9f623626b401bf0b6f426de3","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b1fc7b510198e711d1eda76e5bd3197552d24dd61a7e925c04c4bd16c63362d5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b1fc7b510198e711d1eda76e5bd3197552d24dd61a7e925c04c4bd16c63362d5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b1fc7b510198e711d1eda76e5bd3197552d24dd61a7e925c04c4bd16c63362d5?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/casadelajusticia.com\/en"],"url":"https:\/\/casadelajusticia.com\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/casadelajusticia.com\/en\/wp-json\/wp\/v2\/posts\/9029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadelajusticia.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadelajusticia.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadelajusticia.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/casadelajusticia.com\/en\/wp-json\/wp\/v2\/comments?post=9029"}],"version-history":[{"count":2,"href":"https:\/\/casadelajusticia.com\/en\/wp-json\/wp\/v2\/posts\/9029\/revisions"}],"predecessor-version":[{"id":9252,"href":"https:\/\/casadelajusticia.com\/en\/wp-json\/wp\/v2\/posts\/9029\/revisions\/9252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadelajusticia.com\/en\/wp-json\/wp\/v2\/media\/9031"}],"wp:attachment":[{"href":"https:\/\/casadelajusticia.com\/en\/wp-json\/wp\/v2\/media?parent=9029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadelajusticia.com\/en\/wp-json\/wp\/v2\/categories?post=9029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadelajusticia.com\/en\/wp-json\/wp\/v2\/tags?post=9029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}